{"id":473,"date":"2004-10-13T00:26:41","date_gmt":"2004-10-12T22:26:41","guid":{"rendered":"https:\/\/zeichensetzen-online.de\/?p=473"},"modified":"2025-03-30T10:57:08","modified_gmt":"2025-03-30T08:57:08","slug":"der-islam-und-die-einheit-der-religionen","status":"publish","type":"post","link":"https:\/\/zeichensetzen-online.de\/index.php\/2004\/10\/13\/der-islam-und-die-einheit-der-religionen\/","title":{"rendered":"Der Islam und die Einheit der Religionen"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"473\" class=\"elementor elementor-473\">\n\t\t\t\t\t\t<section class=\"penci-section penci-disSticky penci-structure-10 elementor-section elementor-top-section elementor-element elementor-element-b7a659c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b7a659c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"penci-ercol-100 penci-ercol-order-1 penci-sticky-ct    elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-46de44f\" data-id=\"46de44f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a033328 elementor-widget elementor-widget-penci-fancy_heading\" data-id=\"a033328\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"penci-fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"penci-fancy-heading penci-heading-text-left pc-fctline\">\n\t\t\t<div class=\"penci-fancy-heading-inner\">\n\t\t\t\t<div class=\"penci-heading-subtitle\">Kofo Essen, 13. Oktober 2004<\/div><h2 class=\"penci-heading-title\"><span class=\"inner-tit\">Der Islam und die Einheit der Religionen<\/span><\/h2><div class=\"penci-separator penci-separator- penci-separator-left\"><span class=\"penci-sep_holder penci-sep_holder_l\"><span class=\"penci-sep_line\"><\/span><\/span><span class=\"penci-sep_holder penci-sep_holder_r\"><span class=\"penci-sep_line\"><\/span><\/span><\/div><div class=\"penci-heading-content entry-content\"><p>Referent: Ege Karar<\/p>\n<\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"penci-section penci-disSticky penci-structure-10 elementor-section elementor-top-section elementor-element elementor-element-6ee1909 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6ee1909\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"penci-ercol-100 penci-ercol-order-1 penci-sticky-ct    elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-425c725\" data-id=\"425c725\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e73c19b elementor-widget elementor-widget-text-editor\" data-id=\"e73c19b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Ein neuer Besucher-Rekord: Ungef\u00e4hr 180 G\u00e4ste kamen zu diesem Kofo-Abend. Das zeigt das gro\u00dfe Interesse an diesem Thema. Dieses Mal waren auch sehr viele Jugendliche gekommen.<\/p><p>Nach den Terroranschl\u00e4gen der letzten Jahre \u2013 besonders nach dem 11. September 2001 &#8211; gibt es gro\u00dfe Vorurteile gegen den Islam. Die Medien zeigen gerne gewaltt\u00e4tige Terroristen und verschleierte Frauen. Viele Menschen denken: Islam bedeutet Terror, Gewalt, Frauenunterdr\u00fcckung. Die zahlreichen friedliebenden, toleranten und weltoffenen Muslime leiden unter diesen Stereotypen (= falsche, vereinfachte, ungerechte Urteile). Es gibt aber auch terroristische Muslime (\u201eIslamisten\u201c), sie haben den Islam nicht verstanden und verst\u00e4rken dieses falsche Bild.<\/p><p>Ege m\u00f6chte mit seinem Referat Vorurteile widerlegen, auf die urspr\u00fcngliche Bedeutung von \u201eIslam\u201c hinweisen und f\u00fcr ein friedliches Zusammenleben der Religionsgruppen werben.<\/p><p>Bastienne Rehe dolmetscht f\u00fcr Pfarrer Emler<br \/>Winny <br \/>Hier ist der ausf\u00fchrliche Bericht (pdf-Format)<\/p><p>Bericht in der DGZ 1\/2005 <br \/>(Bericht in der DGZ 1\/2005 mit freundlicher Genehmigung der Redaktion)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"penci-section penci-disSticky penci-structure-10 elementor-section elementor-top-section elementor-element elementor-element-4f9d2ed elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4f9d2ed\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"penci-ercol-100 penci-ercol-order-1 penci-sticky-ct    elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c59d249\" data-id=\"c59d249\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-083cb85 elementor-widget elementor-widget-gallery\" data-id=\"083cb85\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Kofo Essen, 13. Oktober 2004 Der Islam und die Einheit der Religionen Referent: Ege Karar Ein neuer Besucher-Rekord: Ungef\u00e4hr 180 G\u00e4ste kamen zu diesem Kofo-Abend. Das zeigt das gro\u00dfe Interesse&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_lmt_disableupdate":"","_lmt_disable":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[6,152],"tags":[],"class_list":["post-473","post","type-post","status-publish","format-standard","hentry","category-jahrgang-2004","category-oktober-jahrgang-2004"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Kofo Essen, 13. Oktober 2004Der Islam und die Einheit der ReligionenReferent: Ege Karar Ein neuer Besucher-Rekord: Ungef\u00e4hr 180 G\u00e4ste kamen zu diesem Kofo-Abend. Das zeigt das gro\u00dfe Interesse an diesem Thema. Dieses Mal waren auch sehr viele Jugendliche gekommen.Nach den Terroranschl\u00e4gen der letzten Jahre \u2013 besonders nach dem 11. September 2001 \u2013 gibt es gro\u00dfe\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"ulbricht\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/zeichensetzen-online.de\/index.php\/2004\/10\/13\/der-islam-und-die-einheit-der-religionen\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"zeichensetzen-online - F\u00f6rderverein Geh\u00f6rlosenkultur in Essen e.V.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Der Islam und die Einheit der Religionen - zeichensetzen-online\" \/>\n\t\t<meta property=\"og:description\" content=\"Kofo Essen, 13. Oktober 2004Der Islam und die Einheit der ReligionenReferent: Ege Karar Ein neuer Besucher-Rekord: Ungef\u00e4hr 180 G\u00e4ste kamen zu diesem Kofo-Abend. Das zeigt das gro\u00dfe Interesse an diesem Thema. Dieses Mal waren auch sehr viele Jugendliche gekommen.Nach den Terroranschl\u00e4gen der letzten Jahre \u2013 besonders nach dem 11. September 2001 \u2013 gibt es gro\u00dfe\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/zeichensetzen-online.de\/index.php\/2004\/10\/13\/der-islam-und-die-einheit-der-religionen\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/zeichensetzen-online.de\/wp-content\/uploads\/2023\/03\/zeichen-setzen-logo.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/zeichensetzen-online.de\/wp-content\/uploads\/2023\/03\/zeichen-setzen-logo.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2004-10-12T22:26:41+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-03-30T08:57:08+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Der Islam und die Einheit der Religionen - zeichensetzen-online\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Kofo Essen, 13. Oktober 2004Der Islam und die Einheit der ReligionenReferent: Ege Karar Ein neuer Besucher-Rekord: Ungef\u00e4hr 180 G\u00e4ste kamen zu diesem Kofo-Abend. Das zeigt das gro\u00dfe Interesse an diesem Thema. Dieses Mal waren auch sehr viele Jugendliche gekommen.Nach den Terroranschl\u00e4gen der letzten Jahre \u2013 besonders nach dem 11. September 2001 \u2013 gibt es gro\u00dfe\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/zeichensetzen-online.de\/wp-content\/uploads\/2023\/03\/zeichen-setzen-logo.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/zeichensetzen-online.de\\\/index.php\\\/2004\\\/10\\\/13\\\/der-islam-und-die-einheit-der-religionen\\\/#blogposting\",\"name\":\"Der Islam und die Einheit der Religionen - zeichensetzen-online\",\"headline\":\"Der Islam und die Einheit der Religionen\",\"author\":{\"@id\":\"https:\\\/\\\/zeichensetzen-online.de\\\/index.php\\\/author\\\/ulbricht\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/zeichensetzen-online.de\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/zeichensetzen-online.de\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/zeichen-setzen-logo.jpg\",\"@id\":\"https:\\\/\\\/zeichensetzen-online.de\\\/#articleImage\",\"width\":1000,\"height\":500,\"caption\":\"Zeichen setzen!\"},\"datePublished\":\"2004-10-13T00:26:41+02:00\",\"dateModified\":\"2025-03-30T10:57:08+02:00\",\"inLanguage\":\"de-DE\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/zeichensetzen-online.de\\\/index.php\\\/2004\\\/10\\\/13\\\/der-islam-und-die-einheit-der-religionen\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/zeichensetzen-online.de\\\/index.php\\\/2004\\\/10\\\/13\\\/der-islam-und-die-einheit-der-religionen\\\/#webpage\"},\"articleSection\":\"2004, Oktober\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zeichensetzen-online.de\\\/index.php\\\/2004\\\/10\\\/13\\\/der-islam-und-die-einheit-der-religionen\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/zeichensetzen-online.de#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/zeichensetzen-online.de\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/zeichensetzen-online.de\\\/index.php\\\/category\\\/jahrgang-2004\\\/#listItem\",\"name\":\"2004\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/zeichensetzen-online.de\\\/index.php\\\/category\\\/jahrgang-2004\\\/#listItem\",\"position\":2,\"name\":\"2004\",\"item\":\"https:\\\/\\\/zeichensetzen-online.de\\\/index.php\\\/category\\\/jahrgang-2004\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/zeichensetzen-online.de\\\/index.php\\\/category\\\/jahrgang-2004\\\/oktober-jahrgang-2004\\\/#listItem\",\"name\":\"Oktober\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/zeichensetzen-online.de#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/zeichensetzen-online.de\\\/index.php\\\/category\\\/jahrgang-2004\\\/oktober-jahrgang-2004\\\/#listItem\",\"position\":3,\"name\":\"Oktober\",\"item\":\"https:\\\/\\\/zeichensetzen-online.de\\\/index.php\\\/category\\\/jahrgang-2004\\\/oktober-jahrgang-2004\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/zeichensetzen-online.de\\\/index.php\\\/2004\\\/10\\\/13\\\/der-islam-und-die-einheit-der-religionen\\\/#listItem\",\"name\":\"Der Islam und die Einheit der Religionen\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/zeichensetzen-online.de\\\/index.php\\\/category\\\/jahrgang-2004\\\/#listItem\",\"name\":\"2004\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/zeichensetzen-online.de\\\/index.php\\\/2004\\\/10\\\/13\\\/der-islam-und-die-einheit-der-religionen\\\/#listItem\",\"position\":4,\"name\":\"Der Islam und die Einheit der Religionen\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/zeichensetzen-online.de\\\/index.php\\\/category\\\/jahrgang-2004\\\/oktober-jahrgang-2004\\\/#listItem\",\"name\":\"Oktober\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zeichensetzen-online.de\\\/#organization\",\"name\":\"zeichensetzen online\",\"description\":\"F\\u00f6rderverein Geh\\u00f6rlosenkultur in Essen e.V.\",\"url\":\"https:\\\/\\\/zeichensetzen-online.de\\\/\",\"telephone\":\"+4917625477825\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/zeichensetzen-online.de\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/zeichen-setzen-logo.jpg\",\"@id\":\"https:\\\/\\\/zeichensetzen-online.de\\\/index.php\\\/2004\\\/10\\\/13\\\/der-islam-und-die-einheit-der-religionen\\\/#organizationLogo\",\"width\":1000,\"height\":500,\"caption\":\"Zeichen setzen!\"},\"image\":{\"@id\":\"https:\\\/\\\/zeichensetzen-online.de\\\/index.php\\\/2004\\\/10\\\/13\\\/der-islam-und-die-einheit-der-religionen\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/zeichensetzen-online.de\\\/index.php\\\/author\\\/ulbricht\\\/#author\",\"url\":\"https:\\\/\\\/zeichensetzen-online.de\\\/index.php\\\/author\\\/ulbricht\\\/\",\"name\":\"ulbricht\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/zeichensetzen-online.de\\\/index.php\\\/2004\\\/10\\\/13\\\/der-islam-und-die-einheit-der-religionen\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/31346f7c751aa90358976f6f17fcb9eedc81d912b3c644db447111a77a5bbc99?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"ulbricht\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zeichensetzen-online.de\\\/index.php\\\/2004\\\/10\\\/13\\\/der-islam-und-die-einheit-der-religionen\\\/#webpage\",\"url\":\"https:\\\/\\\/zeichensetzen-online.de\\\/index.php\\\/2004\\\/10\\\/13\\\/der-islam-und-die-einheit-der-religionen\\\/\",\"name\":\"Der Islam und die Einheit der Religionen - zeichensetzen-online\",\"description\":\"Kofo Essen, 13. Oktober 2004Der Islam und die Einheit der ReligionenReferent: Ege Karar Ein neuer Besucher-Rekord: Ungef\\u00e4hr 180 G\\u00e4ste kamen zu diesem Kofo-Abend. Das zeigt das gro\\u00dfe Interesse an diesem Thema. Dieses Mal waren auch sehr viele Jugendliche gekommen.Nach den Terroranschl\\u00e4gen der letzten Jahre \\u2013 besonders nach dem 11. September 2001 \\u2013 gibt es gro\\u00dfe\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zeichensetzen-online.de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zeichensetzen-online.de\\\/index.php\\\/2004\\\/10\\\/13\\\/der-islam-und-die-einheit-der-religionen\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/zeichensetzen-online.de\\\/index.php\\\/author\\\/ulbricht\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/zeichensetzen-online.de\\\/index.php\\\/author\\\/ulbricht\\\/#author\"},\"datePublished\":\"2004-10-13T00:26:41+02:00\",\"dateModified\":\"2025-03-30T10:57:08+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zeichensetzen-online.de\\\/#website\",\"url\":\"https:\\\/\\\/zeichensetzen-online.de\\\/\",\"name\":\"zeichensetzen-online\",\"alternateName\":\"zeichensetzen\",\"description\":\"F\\u00f6rderverein Geh\\u00f6rlosenkultur in Essen e.V.\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/zeichensetzen-online.de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Der Islam und die Einheit der Religionen - zeichensetzen-online","description":"Kofo Essen, 13. Oktober 2004Der Islam und die Einheit der ReligionenReferent: Ege Karar Ein neuer Besucher-Rekord: Ungef\u00e4hr 180 G\u00e4ste kamen zu diesem Kofo-Abend. Das zeigt das gro\u00dfe Interesse an diesem Thema. Dieses Mal waren auch sehr viele Jugendliche gekommen.Nach den Terroranschl\u00e4gen der letzten Jahre \u2013 besonders nach dem 11. September 2001 \u2013 gibt es gro\u00dfe","canonical_url":"https:\/\/zeichensetzen-online.de\/index.php\/2004\/10\/13\/der-islam-und-die-einheit-der-religionen\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/zeichensetzen-online.de\/index.php\/2004\/10\/13\/der-islam-und-die-einheit-der-religionen\/#blogposting","name":"Der Islam und die Einheit der Religionen - zeichensetzen-online","headline":"Der Islam und die Einheit der Religionen","author":{"@id":"https:\/\/zeichensetzen-online.de\/index.php\/author\/ulbricht\/#author"},"publisher":{"@id":"https:\/\/zeichensetzen-online.de\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/zeichensetzen-online.de\/wp-content\/uploads\/2023\/03\/zeichen-setzen-logo.jpg","@id":"https:\/\/zeichensetzen-online.de\/#articleImage","width":1000,"height":500,"caption":"Zeichen setzen!"},"datePublished":"2004-10-13T00:26:41+02:00","dateModified":"2025-03-30T10:57:08+02:00","inLanguage":"de-DE","mainEntityOfPage":{"@id":"https:\/\/zeichensetzen-online.de\/index.php\/2004\/10\/13\/der-islam-und-die-einheit-der-religionen\/#webpage"},"isPartOf":{"@id":"https:\/\/zeichensetzen-online.de\/index.php\/2004\/10\/13\/der-islam-und-die-einheit-der-religionen\/#webpage"},"articleSection":"2004, Oktober"},{"@type":"BreadcrumbList","@id":"https:\/\/zeichensetzen-online.de\/index.php\/2004\/10\/13\/der-islam-und-die-einheit-der-religionen\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/zeichensetzen-online.de#listItem","position":1,"name":"Home","item":"https:\/\/zeichensetzen-online.de","nextItem":{"@type":"ListItem","@id":"https:\/\/zeichensetzen-online.de\/index.php\/category\/jahrgang-2004\/#listItem","name":"2004"}},{"@type":"ListItem","@id":"https:\/\/zeichensetzen-online.de\/index.php\/category\/jahrgang-2004\/#listItem","position":2,"name":"2004","item":"https:\/\/zeichensetzen-online.de\/index.php\/category\/jahrgang-2004\/","nextItem":{"@type":"ListItem","@id":"https:\/\/zeichensetzen-online.de\/index.php\/category\/jahrgang-2004\/oktober-jahrgang-2004\/#listItem","name":"Oktober"},"previousItem":{"@type":"ListItem","@id":"https:\/\/zeichensetzen-online.de#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/zeichensetzen-online.de\/index.php\/category\/jahrgang-2004\/oktober-jahrgang-2004\/#listItem","position":3,"name":"Oktober","item":"https:\/\/zeichensetzen-online.de\/index.php\/category\/jahrgang-2004\/oktober-jahrgang-2004\/","nextItem":{"@type":"ListItem","@id":"https:\/\/zeichensetzen-online.de\/index.php\/2004\/10\/13\/der-islam-und-die-einheit-der-religionen\/#listItem","name":"Der Islam und die Einheit der Religionen"},"previousItem":{"@type":"ListItem","@id":"https:\/\/zeichensetzen-online.de\/index.php\/category\/jahrgang-2004\/#listItem","name":"2004"}},{"@type":"ListItem","@id":"https:\/\/zeichensetzen-online.de\/index.php\/2004\/10\/13\/der-islam-und-die-einheit-der-religionen\/#listItem","position":4,"name":"Der Islam und die Einheit der Religionen","previousItem":{"@type":"ListItem","@id":"https:\/\/zeichensetzen-online.de\/index.php\/category\/jahrgang-2004\/oktober-jahrgang-2004\/#listItem","name":"Oktober"}}]},{"@type":"Organization","@id":"https:\/\/zeichensetzen-online.de\/#organization","name":"zeichensetzen online","description":"F\u00f6rderverein Geh\u00f6rlosenkultur in Essen e.V.","url":"https:\/\/zeichensetzen-online.de\/","telephone":"+4917625477825","logo":{"@type":"ImageObject","url":"https:\/\/zeichensetzen-online.de\/wp-content\/uploads\/2023\/03\/zeichen-setzen-logo.jpg","@id":"https:\/\/zeichensetzen-online.de\/index.php\/2004\/10\/13\/der-islam-und-die-einheit-der-religionen\/#organizationLogo","width":1000,"height":500,"caption":"Zeichen setzen!"},"image":{"@id":"https:\/\/zeichensetzen-online.de\/index.php\/2004\/10\/13\/der-islam-und-die-einheit-der-religionen\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/zeichensetzen-online.de\/index.php\/author\/ulbricht\/#author","url":"https:\/\/zeichensetzen-online.de\/index.php\/author\/ulbricht\/","name":"ulbricht","image":{"@type":"ImageObject","@id":"https:\/\/zeichensetzen-online.de\/index.php\/2004\/10\/13\/der-islam-und-die-einheit-der-religionen\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/31346f7c751aa90358976f6f17fcb9eedc81d912b3c644db447111a77a5bbc99?s=96&d=mm&r=g","width":96,"height":96,"caption":"ulbricht"}},{"@type":"WebPage","@id":"https:\/\/zeichensetzen-online.de\/index.php\/2004\/10\/13\/der-islam-und-die-einheit-der-religionen\/#webpage","url":"https:\/\/zeichensetzen-online.de\/index.php\/2004\/10\/13\/der-islam-und-die-einheit-der-religionen\/","name":"Der Islam und die Einheit der Religionen - zeichensetzen-online","description":"Kofo Essen, 13. Oktober 2004Der Islam und die Einheit der ReligionenReferent: Ege Karar Ein neuer Besucher-Rekord: Ungef\u00e4hr 180 G\u00e4ste kamen zu diesem Kofo-Abend. Das zeigt das gro\u00dfe Interesse an diesem Thema. Dieses Mal waren auch sehr viele Jugendliche gekommen.Nach den Terroranschl\u00e4gen der letzten Jahre \u2013 besonders nach dem 11. September 2001 \u2013 gibt es gro\u00dfe","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/zeichensetzen-online.de\/#website"},"breadcrumb":{"@id":"https:\/\/zeichensetzen-online.de\/index.php\/2004\/10\/13\/der-islam-und-die-einheit-der-religionen\/#breadcrumblist"},"author":{"@id":"https:\/\/zeichensetzen-online.de\/index.php\/author\/ulbricht\/#author"},"creator":{"@id":"https:\/\/zeichensetzen-online.de\/index.php\/author\/ulbricht\/#author"},"datePublished":"2004-10-13T00:26:41+02:00","dateModified":"2025-03-30T10:57:08+02:00"},{"@type":"WebSite","@id":"https:\/\/zeichensetzen-online.de\/#website","url":"https:\/\/zeichensetzen-online.de\/","name":"zeichensetzen-online","alternateName":"zeichensetzen","description":"F\u00f6rderverein Geh\u00f6rlosenkultur in Essen e.V.","inLanguage":"de-DE","publisher":{"@id":"https:\/\/zeichensetzen-online.de\/#organization"}}]},"og:locale":"de_DE","og:site_name":"zeichensetzen-online - F\u00f6rderverein Geh\u00f6rlosenkultur in Essen e.V.","og:type":"article","og:title":"Der Islam und die Einheit der Religionen - zeichensetzen-online","og:description":"Kofo Essen, 13. Oktober 2004Der Islam und die Einheit der ReligionenReferent: Ege Karar Ein neuer Besucher-Rekord: Ungef\u00e4hr 180 G\u00e4ste kamen zu diesem Kofo-Abend. Das zeigt das gro\u00dfe Interesse an diesem Thema. Dieses Mal waren auch sehr viele Jugendliche gekommen.Nach den Terroranschl\u00e4gen der letzten Jahre \u2013 besonders nach dem 11. September 2001 \u2013 gibt es gro\u00dfe","og:url":"https:\/\/zeichensetzen-online.de\/index.php\/2004\/10\/13\/der-islam-und-die-einheit-der-religionen\/","og:image":"https:\/\/zeichensetzen-online.de\/wp-content\/uploads\/2023\/03\/zeichen-setzen-logo.jpg","og:image:secure_url":"https:\/\/zeichensetzen-online.de\/wp-content\/uploads\/2023\/03\/zeichen-setzen-logo.jpg","og:image:width":1000,"og:image:height":500,"article:published_time":"2004-10-12T22:26:41+00:00","article:modified_time":"2025-03-30T08:57:08+00:00","twitter:card":"summary_large_image","twitter:title":"Der Islam und die Einheit der Religionen - zeichensetzen-online","twitter:description":"Kofo Essen, 13. Oktober 2004Der Islam und die Einheit der ReligionenReferent: Ege Karar Ein neuer Besucher-Rekord: Ungef\u00e4hr 180 G\u00e4ste kamen zu diesem Kofo-Abend. Das zeigt das gro\u00dfe Interesse an diesem Thema. Dieses Mal waren auch sehr viele Jugendliche gekommen.Nach den Terroranschl\u00e4gen der letzten Jahre \u2013 besonders nach dem 11. September 2001 \u2013 gibt es gro\u00dfe","twitter:image":"https:\/\/zeichensetzen-online.de\/wp-content\/uploads\/2023\/03\/zeichen-setzen-logo.jpg"},"aioseo_meta_data":{"post_id":"473","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-11-15 21:30:59","updated":"2025-10-12 22:13:46","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/zeichensetzen-online.de\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/zeichensetzen-online.de\/index.php\/category\/jahrgang-2004\/\" title=\"2004\">2004<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/zeichensetzen-online.de\/index.php\/category\/jahrgang-2004\/oktober-jahrgang-2004\/\" title=\"Oktober\">Oktober<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tDer Islam und die Einheit der Religionen\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/zeichensetzen-online.de"},{"label":"2004","link":"https:\/\/zeichensetzen-online.de\/index.php\/category\/jahrgang-2004\/"},{"label":"Oktober","link":"https:\/\/zeichensetzen-online.de\/index.php\/category\/jahrgang-2004\/oktober-jahrgang-2004\/"},{"label":"Der Islam und die Einheit der Religionen","link":"https:\/\/zeichensetzen-online.de\/index.php\/2004\/10\/13\/der-islam-und-die-einheit-der-religionen\/"}],"_links":{"self":[{"href":"https:\/\/zeichensetzen-online.de\/index.php\/wp-json\/wp\/v2\/posts\/473","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zeichensetzen-online.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zeichensetzen-online.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zeichensetzen-online.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zeichensetzen-online.de\/index.php\/wp-json\/wp\/v2\/comments?post=473"}],"version-history":[{"count":15,"href":"https:\/\/zeichensetzen-online.de\/index.php\/wp-json\/wp\/v2\/posts\/473\/revisions"}],"predecessor-version":[{"id":5358,"href":"https:\/\/zeichensetzen-online.de\/index.php\/wp-json\/wp\/v2\/posts\/473\/revisions\/5358"}],"wp:attachment":[{"href":"https:\/\/zeichensetzen-online.de\/index.php\/wp-json\/wp\/v2\/media?parent=473"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zeichensetzen-online.de\/index.php\/wp-json\/wp\/v2\/categories?post=473"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zeichensetzen-online.de\/index.php\/wp-json\/wp\/v2\/tags?post=473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}